{"id":452,"count":1,"description":"","link":"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/","name":"patina per la merc\u00e8","slug":"patina-per-la-merce","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arxius de patina per la merc\u00e8 - Escola Oficial Patinatge Inline<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de patina per la merc\u00e8 - Escola Oficial Patinatge Inline\" \/>\n<meta property=\"og:url\" content=\"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/\" \/>\n<meta property=\"og:site_name\" content=\"Escola Oficial Patinatge Inline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/\",\"url\":\"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/\",\"name\":\"Arxius de patina per la merc\u00e8 - Escola Oficial Patinatge Inline\",\"isPartOf\":{\"@id\":\"https:\/\/escolapatinatge.com\/ca\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/escolapatinatge.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"patina per la merc\u00e8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/escolapatinatge.com\/ca\/#website\",\"url\":\"https:\/\/escolapatinatge.com\/ca\/\",\"name\":\"Escola Oficial Patinatge Inline\",\"description\":\"Classes de patinatge a Barcelona. Apr\u00e8n a patinar a la millor escola de patinatge. Cursos per totes les edats i nivells.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/escolapatinatge.com\/ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arxius de patina per la merc\u00e8 - Escola Oficial Patinatge Inline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/","og_locale":"ca_ES","og_type":"article","og_title":"Arxius de patina per la merc\u00e8 - Escola Oficial Patinatge Inline","og_url":"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/","og_site_name":"Escola Oficial Patinatge Inline","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/","url":"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/","name":"Arxius de patina per la merc\u00e8 - Escola Oficial Patinatge Inline","isPartOf":{"@id":"https:\/\/escolapatinatge.com\/ca\/#website"},"breadcrumb":{"@id":"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"http:\/\/escolapatinatge.com\/ca\/tag\/patina-per-la-merce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/escolapatinatge.com\/ca\/"},{"@type":"ListItem","position":2,"name":"patina per la merc\u00e8"}]},{"@type":"WebSite","@id":"https:\/\/escolapatinatge.com\/ca\/#website","url":"https:\/\/escolapatinatge.com\/ca\/","name":"Escola Oficial Patinatge Inline","description":"Classes de patinatge a Barcelona. Apr\u00e8n a patinar a la millor escola de patinatge. Cursos per totes les edats i nivells.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escolapatinatge.com\/ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"http:\/\/escolapatinatge.com\/ca\/wp-json\/wp\/v2\/tags\/452"}],"collection":[{"href":"http:\/\/escolapatinatge.com\/ca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/escolapatinatge.com\/ca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/escolapatinatge.com\/ca\/wp-json\/wp\/v2\/posts?tags=452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}